{"id":4032,"date":"2024-01-31T15:01:31","date_gmt":"2024-01-31T15:01:31","guid":{"rendered":"https:\/\/www.joe-rainey.com\/?p=4032"},"modified":"2024-01-31T15:01:36","modified_gmt":"2024-01-31T15:01:36","slug":"audionovel-experience-between-a-book-and-a-movie","status":"publish","type":"post","link":"https:\/\/www.joe-rainey.com\/es\/audionovel-experience-between-a-book-and-a-movie\/","title":{"rendered":"Audionovelas: Entre un libro y una pel\u00edcula"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Hace dos a\u00f1os comenc\u00e9 a escuchar audiolibros y r\u00e1pidamente me convert\u00ed en un gran fan. Desde entonces, he estado reflexionando sobre el tema y he llegado a algunas conclusiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar, creo que llegu\u00e9 un poco tarde a los audiolibros. Sol\u00eda ser esc\u00e9ptico y pensaba que los audiolibros eran para lectores perezosos, y que preferir\u00eda leer el libro. Pero estaba equivocado al respecto, y me alegra haberle dado una oportunidad a los audiolibros. Es una experiencia diferente que puede coexistir con la lectura regular de libros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los audiolibros han ido ganando popularidad en los \u00faltimos a\u00f1os, y por el momento, es una tendencia al alza. Han existido durante muchas d\u00e9cadas, pero nunca fueron tan accesibles como lo son hoy, gracias a los formatos digitales y los servicios en l\u00ednea de transmisi\u00f3n de audiolibros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en fin, lo primero que me llam\u00f3 la atenci\u00f3n cuando comenc\u00e9 a escuchar audiolibros fue lo natural que resultaba la experiencia. Tiene sentido. Los humanos han contado historias y han transmitido informaci\u00f3n entre ellos de manera oral desde la invenci\u00f3n del lenguaje. Supongo que incluso podr\u00edamos decir que los audiolibros son un medio m\u00e1s natural para nosotros para transmitir informaci\u00f3n que los libros regulares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi tipo favorito es la audionovela. Regularmente escucho una audionovela durante una hora o dos cada noche antes de dormir, y mi conclusi\u00f3n es que es una experiencia similar a ver una pel\u00edcula, especialmente si escuchas en completa oscuridad con los ojos cerrados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63.jpg\" alt=\"\" class=\"wp-image-4034\" srcset=\"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63.jpg 1024w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63-300x300.jpg 300w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63-150x150.jpg 150w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63-768x768.jpg 768w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63-12x12.jpg 12w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63-600x600.jpg 600w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63-100x100.jpg 100w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pretty_blackheared_girl_in_a_couch_with_headphones_cd3f708c-f3d0-4b09-b88e-5b5431fa5f63-560x560.jpg 560w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Perm\u00edteme explicar. Cuando est\u00e1s leyendo una novela, obviamente debes enfocar tu mente en leer y procesar las palabras. Solo esto requiere un buen esfuerzo. Tambi\u00e9n tienes algunas distracciones adicionales con las que debes lidiar, como el hecho de que a\u00fan puedes ver parte del mundo que te rodea, incluso si est\u00e1s tratando de enfocar tus ojos en el texto frente a ti. Adem\u00e1s, tu entorno puede ser ruidoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, si intentas imaginar lo que est\u00e1 sucediendo en la novela mientras lees, tu imaginaci\u00f3n no ser\u00e1 tan eficiente como podr\u00eda ser, ya que est\u00e1s perdiendo mucha energ\u00eda mental lidiando con esas otras cosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, sostener un libro, lector electr\u00f3nico, o lo que sea, tambi\u00e9n puede resultar cansado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed es donde entra la audionovela. Dado que solo te est\u00e1s enfocando en escuchar y no est\u00e1s desperdiciando los recursos mentales en otras cosas, tu imaginaci\u00f3n es libre para usar su m\u00e1ximo potencial, por lo que puedes obtener una experiencia muy poderosa e inmersiva, similar a ver una pel\u00edcula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante tener en cuenta que nuestro sistema de escucha est\u00e1 ajustado de una manera que nos hace, de cierta forma, \"ver el mundo\" a trav\u00e9s de nuestra audici\u00f3n, incluso si no somos conscientes regularmente de que esto est\u00e1 sucediendo. Esto se llama \"integraci\u00f3n multisensorial\" y se refiere a c\u00f3mo nuestro cerebro es capaz de integrar informaci\u00f3n de m\u00faltiples sentidos, incluidos la vista y el o\u00eddo, para crear una imagen m\u00e1s precisa y completa del mundo que nos rodea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, una de las razones por las que las audionovelas son realmente buenas para ayudarnos a imaginar la narraci\u00f3n mejor que simplemente leer es que nuestros cerebros est\u00e1n acostumbrados a integrar informaci\u00f3n auditiva en la forma en que percibimos el mundo. Escuchar a alguien narrar una audionovela podr\u00eda estimular ese aspecto de integraci\u00f3n multisensorial en nuestros cerebros, que usamos inconscientemente todos los d\u00edas, y ayudarnos autom\u00e1ticamente a llenar los vac\u00edos en nuestra imaginaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1920\" height=\"1920\" src=\"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5.jpg\" alt=\"\" class=\"wp-image-4035\" srcset=\"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5.jpg 1920w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-300x300.jpg 300w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-1024x1024.jpg 1024w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-150x150.jpg 150w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-768x768.jpg 768w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-1536x1536.jpg 1536w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-12x12.jpg 12w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-600x600.jpg 600w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-100x100.jpg 100w, https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/joe_rainey_a_pair_of_headphones_are_depicted_with_a_city_scene__31a70ac7-60f6-4a46-971d-da347d0fd5c5-560x560.jpg 560w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, escuchar la voz de un narrador tambi\u00e9n puede agregar profundidad y matices emocionales a la historia, ya que el tono, el ritmo y la inflexi\u00f3n de su voz pueden transmitir una variedad de emociones y significados que podr\u00edan ser dif\u00edciles de capturar solo con palabras escritas. Esto puede hacer que la experiencia de escuchar una audionovela sea m\u00e1s atractiva y emocionalmente resonante, ya que el oyente puede conectarse con la historia a un nivel m\u00e1s profundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n hay audionovelas que cuentan con narraciones de un elenco m\u00faltiple, efectos de sonido e incluso m\u00fasica. Estas pueden crear una experiencia a\u00fan m\u00e1s inmersiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por supuesto, todav\u00eda necesitas concentrarte y hacer un esfuerzo. Escuchar una audionovela puede ser una experiencia similar a ver una pel\u00edcula, pero no es tan f\u00e1cil como ver televisi\u00f3n. Todav\u00eda debes dirigir tu atenci\u00f3n al sonido y concentrarte en las palabras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto se vuelve m\u00e1s f\u00e1cil. Si dejas ir el resto de tus pensamientos y solo ocupas tu atenci\u00f3n en la audionovela, puedes entrar en este tipo de estado donde dejas que tu imaginaci\u00f3n fluya libremente con lo que est\u00e1s escuchando, en tiempo real. Pru\u00e9balo con los ojos cerrados, con auriculares con cancelaci\u00f3n de ruido, en total oscuridad. Buen rollo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Two years ago I started listening to audiobooks, and I quickly became a big fan. Since then, I\u2019ve been giving some thought to the subject and arrived at a few conclusions. First of all, I think I was somewhat late to getting into audiobooks. The thing is, I used to be skeptical and thought audiobooks [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[52,128],"tags":[],"class_list":["post-4032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thoughts","category-psychology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Audionovels: Between a Book and a Movie - Joe Rainey<\/title>\n<meta name=\"description\" content=\"Discover the audionovel experience and its unique charm and movie-like journey in my article on this immersive form of modern storytelling.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Audionovels: Between a Book and a Movie - Joe Rainey\" \/>\n<meta property=\"og:description\" content=\"Discover the audionovel experience and its unique charm and movie-like journey in my article on this immersive form of modern storytelling.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/\" \/>\n<meta property=\"og:site_name\" content=\"Joe Rainey\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-31T15:01:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T15:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joe Rainey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joe Rainey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/\"},\"author\":{\"name\":\"Joe Rainey\",\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/#\\\/schema\\\/person\\\/d289d28ce84554c3549688d3ab4531a1\"},\"headline\":\"Audionovels: Between a Book and a Movie\",\"datePublished\":\"2024-01-31T15:01:31+00:00\",\"dateModified\":\"2024-01-31T15:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/\"},\"wordCount\":794,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/#\\\/schema\\\/person\\\/d289d28ce84554c3549688d3ab4531a1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joe-rainey.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg\",\"articleSection\":[\"Assorted Thoughts\",\"Psychology\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/\",\"url\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/\",\"name\":\"Audionovels: Between a Book and a Movie - Joe Rainey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joe-rainey.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg\",\"datePublished\":\"2024-01-31T15:01:31+00:00\",\"dateModified\":\"2024-01-31T15:01:36+00:00\",\"description\":\"Discover the audionovel experience and its unique charm and movie-like journey in my article on this immersive form of modern storytelling.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joe-rainey.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joe-rainey.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/es\\\/experiencia-audionovela-entre-un-libro-y-una-pelicula\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joe-rainey.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Audionovels: Between a Book and a Movie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/#website\",\"url\":\"https:\\\/\\\/www.joe-rainey.com\\\/\",\"name\":\"Joe Rainey\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/#\\\/schema\\\/person\\\/d289d28ce84554c3549688d3ab4531a1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joe-rainey.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.joe-rainey.com\\\/#\\\/schema\\\/person\\\/d289d28ce84554c3549688d3ab4531a1\",\"name\":\"Joe Rainey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e159ac7d5ce51fcb77106aa31a4efcca6a824386af1ccb2ab8bf75bafd88a72f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e159ac7d5ce51fcb77106aa31a4efcca6a824386af1ccb2ab8bf75bafd88a72f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e159ac7d5ce51fcb77106aa31a4efcca6a824386af1ccb2ab8bf75bafd88a72f?s=96&d=mm&r=g\",\"caption\":\"Joe Rainey\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e159ac7d5ce51fcb77106aa31a4efcca6a824386af1ccb2ab8bf75bafd88a72f?s=96&d=mm&r=g\"},\"description\":\"Hi. I'm a solo artist and music composer for films and video games. I also write a blog, mostly music related, but also include other things of my interest.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Audionovelas: Entre un libro y una pel\u00edcula - Joe Rainey","description":"Descubre las experienca de la Audionovela, encanto \u00fanico, similar a una pel\u00edcula, en mi art\u00edculo sobre esta forma inmersiva de narraci\u00f3n moderna.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/","og_locale":"es_ES","og_type":"article","og_title":"Audionovels: Between a Book and a Movie - Joe Rainey","og_description":"Discover the audionovel experience and its unique charm and movie-like journey in my article on this immersive form of modern storytelling.","og_url":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/","og_site_name":"Joe Rainey","article_published_time":"2024-01-31T15:01:31+00:00","article_modified_time":"2024-01-31T15:01:36+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg","type":"image\/jpeg"}],"author":"Joe Rainey","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joe Rainey","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/#article","isPartOf":{"@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/"},"author":{"name":"Joe Rainey","@id":"https:\/\/www.joe-rainey.com\/#\/schema\/person\/d289d28ce84554c3549688d3ab4531a1"},"headline":"Audionovels: Between a Book and a Movie","datePublished":"2024-01-31T15:01:31+00:00","dateModified":"2024-01-31T15:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/"},"wordCount":794,"commentCount":0,"publisher":{"@id":"https:\/\/www.joe-rainey.com\/#\/schema\/person\/d289d28ce84554c3549688d3ab4531a1"},"image":{"@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg","articleSection":["Assorted Thoughts","Psychology"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/","url":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/","name":"Audionovelas: Entre un libro y una pel\u00edcula - Joe Rainey","isPartOf":{"@id":"https:\/\/www.joe-rainey.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/#primaryimage"},"image":{"@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg","datePublished":"2024-01-31T15:01:31+00:00","dateModified":"2024-01-31T15:01:36+00:00","description":"Descubre las experienca de la Audionovela, encanto \u00fanico, similar a una pel\u00edcula, en mi art\u00edculo sobre esta forma inmersiva de narraci\u00f3n moderna.","breadcrumb":{"@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/#primaryimage","url":"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg","contentUrl":"https:\/\/www.joe-rainey.com\/wp-content\/uploads\/2024\/01\/DALL\u00b7E-2024-01-21-18.58.25-A-beautiful-woman-wearing-headphones-sitting-with-her-eyes-closed-deeply-engaged-in-an-audionovel.-Surrounding-her-a-simpler-but-imaginative-array-.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.joe-rainey.com\/es\/experiencia-audionovela-entre-un-libro-y-una-pelicula\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joe-rainey.com\/"},{"@type":"ListItem","position":2,"name":"Audionovels: Between a Book and a Movie"}]},{"@type":"WebSite","@id":"https:\/\/www.joe-rainey.com\/#website","url":"https:\/\/www.joe-rainey.com\/","name":"Joe Rainey","description":"","publisher":{"@id":"https:\/\/www.joe-rainey.com\/#\/schema\/person\/d289d28ce84554c3549688d3ab4531a1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joe-rainey.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/www.joe-rainey.com\/#\/schema\/person\/d289d28ce84554c3549688d3ab4531a1","name":"Joe Rainey","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e159ac7d5ce51fcb77106aa31a4efcca6a824386af1ccb2ab8bf75bafd88a72f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e159ac7d5ce51fcb77106aa31a4efcca6a824386af1ccb2ab8bf75bafd88a72f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e159ac7d5ce51fcb77106aa31a4efcca6a824386af1ccb2ab8bf75bafd88a72f?s=96&d=mm&r=g","caption":"Joe Rainey"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/e159ac7d5ce51fcb77106aa31a4efcca6a824386af1ccb2ab8bf75bafd88a72f?s=96&d=mm&r=g"},"description":"Hi. I'm a solo artist and music composer for films and video games. I also write a blog, mostly music related, but also include other things of my interest."}]}},"_links":{"self":[{"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/posts\/4032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/comments?post=4032"}],"version-history":[{"count":7,"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/posts\/4032\/revisions"}],"predecessor-version":[{"id":4055,"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/posts\/4032\/revisions\/4055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/media\/4053"}],"wp:attachment":[{"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/media?parent=4032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/categories?post=4032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joe-rainey.com\/es\/wp-json\/wp\/v2\/tags?post=4032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}